{"id":69,"date":"2021-04-27T09:33:55","date_gmt":"2021-04-27T09:33:55","guid":{"rendered":"https:\/\/b36oyymf.myrdbx.io\/?page_id=69"},"modified":"2026-02-16T13:18:59","modified_gmt":"2026-02-16T13:18:59","slug":"demeter-landwirtschaft","status":"publish","type":"page","link":"https:\/\/alt.linden-gut.eu\/de\/demeter-landwirtschaft\/","title":{"rendered":"Demeter Landwirtschaft"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"69\" class=\"elementor elementor-69\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e3c932e elementor-section-full_width elementor-hidden-phone elementor-section-height-default elementor-section-height-default\" data-id=\"e3c932e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-290efb2\" data-id=\"290efb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bbb456c elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"bbb456c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-373c7a5 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Biohotel Lindengut Demeter Landwirtschaft\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-da2f58a swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Demeter Landwirtschaft<\/div><div class=\"elementor-slide-description\">Unseren Betrieb mit 100 % zertifizierter Bio-Qualit\u00e4t zu f\u00fchren, war uns schon lange ein gro\u00dfes Anliegen. Doch wir wollten noch einen Schritt weiter gehen. Daher beschlossen wir, eine biodynamische Wirtschaftsweise anzuwenden und alles in zertifizierter Demeter-Qualit\u00e4t anzubieten.<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Vorheriger Slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster Slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc1a0dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc1a0dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f38cccd\" data-id=\"f38cccd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31469fb elementor-widget elementor-widget-spacer\" data-id=\"31469fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b19260f elementor-widget elementor-widget-heading\" data-id=\"b19260f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Demeter Landwirtschaft<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc311b0 elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"dc311b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline_zigzag&quot;,&quot;highlighted_text&quot;:&quot;Was ist  \\u00fcberhaupt eine Demeter Landwirtschaft?&quot;,&quot;highlight_animation_duration&quot;:1172,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-headline\">\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">Was ist  \u00fcberhaupt eine Demeter Landwirtschaft?<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1e7ec2 elementor-widget elementor-widget-text-editor\" data-id=\"c1e7ec2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"\"><p>Die Demeter Landwirtschaft am BIO HOTEL LindenGut wird nach biologisch-dynamischen Prinzipien gef\u00fchrt. Diese Methode ist zukunftsweisender Landbau, der vom Menschen ausgehend die geistigen Wirkungszusammenh\u00e4nge in der Natur erkennen will und mit ihnen handelt und gestaltet. Hierbei spielt der geschlossene landwirtschaftliche Betriebsorganismus eine wesentliche Rolle.\u00a0<\/p><\/div><div class=\"\">In einem st\u00e4ndigen Prozess soll er weiter gestaltet und als Organismus h\u00f6herer Ordnung f\u00fcr Mensch und Erde heilsam wirksam werden. Es werden eigens produzierte D\u00fcngemittel integriert und das Zusammenleben von Tieren und Pflanzen ist zentral. Dar\u00fcber hinaus werden kosmische Elemente (wie beispielsweise die Mondphase) mit einbezogen. Selbstverst\u00e4ndlich gelten auch bei dieser Wirtschaftsweise strenge Richtlinien, die es einzuhalten gilt. Prinzipiell kann man sagen, dass diese biodynamische Methode eine sehr urspr\u00fcngliche Art der Landwirtschaft darstellt.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12704c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"12704c5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-df5984a\" data-id=\"df5984a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d40af86 elementor-widget elementor-widget-image\" data-id=\"d40af86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"430\" height=\"284\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/04\/Biohotel-Lindengut-Nachhaltiges-Hotel-3.jpg\" class=\"attachment-full size-full wp-image-342\" alt=\"Biohotel Lindengut Nachhaltiges Hotel\" srcset=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/04\/Biohotel-Lindengut-Nachhaltiges-Hotel-3.jpg 430w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/04\/Biohotel-Lindengut-Nachhaltiges-Hotel-3-300x198.jpg 300w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83f5e37 elementor-widget elementor-widget-image\" data-id=\"83f5e37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"430\" height=\"284\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Hofverkauf-Kartoffeln.jpg\" class=\"attachment-full size-full wp-image-650\" alt=\"Biohotel Lindengut Hofverkauf Demeter Kartoffeln\" srcset=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Hofverkauf-Kartoffeln.jpg 430w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Hofverkauf-Kartoffeln-300x198.jpg 300w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c231a45 elementor-widget elementor-widget-spacer\" data-id=\"c231a45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7adee46\" data-id=\"7adee46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5cd780 elementor-widget elementor-widget-image\" data-id=\"d5cd780\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"430\" height=\"284\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Hofverkauf-Koblauch.jpg\" class=\"attachment-full size-full wp-image-648\" alt=\"Biohotel Lindengut Hofverkauf Demeter Knoblauch\" srcset=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Hofverkauf-Koblauch.jpg 430w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Hofverkauf-Koblauch-300x198.jpg 300w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cab468e elementor-widget elementor-widget-image\" data-id=\"cab468e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"284\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Ziege.jpg\" class=\"attachment-full size-full wp-image-880\" alt=\"\" srcset=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Ziege.jpg 430w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Ziege-300x198.jpg 300w\" sizes=\"(max-width: 430px) 100vw, 430px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f19dfb elementor-widget elementor-widget-spacer\" data-id=\"0f19dfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c6350d2\" data-id=\"c6350d2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebede20 elementor-widget elementor-widget-image\" data-id=\"ebede20\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/elementor\/thumbs\/Biohotel-Lindengut-Demeter-Landwirtschaft-Hofverkauf-Bio-Eier-rmu3ijlef1100y8shetthxouhrzsi5p3k95hb06nm0.jpg\" title=\"Biohotel-Lindengut-Demeter-Landwirtschaft-Hofverkauf-Bio-Eier\" alt=\"Biohotel Lindengut Hofverkauf Demeter Bio-Eier\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c053a0a elementor-widget elementor-widget-spacer\" data-id=\"c053a0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba15962 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba15962\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e8be474\" data-id=\"e8be474\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bfb9fd elementor-widget elementor-widget-spacer\" data-id=\"7bfb9fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30980a8 elementor-widget elementor-widget-text-editor\" data-id=\"30980a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd121b4 elementor-widget elementor-widget-heading\" data-id=\"bd121b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-element elementor-element-1099cd6 elementor-widget elementor-widget-heading\" data-id=\"1099cd6\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><div data-id=\"b348e54\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div><h2>Warum Demeter Landwirtschaft?<\/h2><\/div><\/div><div class=\"elementor-element elementor-element-0979910 elementor-widget elementor-widget-text-editor\" data-id=\"0979910\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-text-editor elementor-clearfix\"><div class=\"\"><p>Unseren Betrieb mit 100 % zertifizierter Bio-Qualit\u00e4t zu f\u00fchren, war uns schon lange ein gro\u00dfes Anliegen. Doch wir wollten noch einen Schritt weiter gehen. Daher beschlossen wir, eine biodynamische Wirtschaftsweise anzuwenden und alles in zertifizierter Demeter-Qualit\u00e4t anzubieten. So k\u00f6nnen wir unseren G\u00e4sten und Kunden die T\u00fcr zu einer hochwertigen Genusswelt er\u00f6ffnen. Die Transparenz sorgt daf\u00fcr, dass unser Motto \u201evom Acker auf den Teller\u201c f\u00fcr die Menschen bei uns live erlebbar gemacht wird. Wenn Sie mehr dar\u00fcber erfahren m\u00f6chten, klicken Sie bitte hier:<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20ac4be elementor-invisible elementor-widget elementor-widget-button\" data-id=\"20ac4be\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/alt.linden-gut.eu\/nachhaltiges-hotel-in-deutschland\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nachhaltiges Hotel in Deutschland<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-349c699 elementor-widget elementor-widget-spacer\" data-id=\"349c699\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-361d8e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"361d8e6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e17b5c8\" data-id=\"e17b5c8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d7de3a elementor-widget elementor-widget-spacer\" data-id=\"3d7de3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c8efbc elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"4c8efbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline_zigzag&quot;,&quot;highlighted_text&quot;:&quot;Die Demeter Landwirtschaft am LindenGut&quot;,&quot;highlight_animation_duration&quot;:1172,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-headline\">\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">Die Demeter Landwirtschaft am LindenGut<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8649821 elementor-widget elementor-widget-text-editor\" data-id=\"8649821\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><div data-id=\"f63b3d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div><p>Unsere biodynamische Demeter Landwirtschaft ist u. a. Hauptlieferant des Biohotel LindenGut, z.B. f\u00fcr unser Fr\u00fchst\u00fcck, Eigenmarken und Veranstaltungen. Denn gesunde Lebensmittel von h\u00f6chster Qualit\u00e4t zu schaffen und dabei unsere nat\u00fcrlichen Lebensgrundlagen (die Pflanzen- und Tierwelt und das soziale Umfeld des Hofes) mit besten Kr\u00e4ften zu f\u00f6rdern, ist unser gemeinsames Ziel.\u00a0<span style=\"color: #111111; font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size );\">Wir bearbeiten derzeit \u00fcber 120 ha landwirtschaftliche Fl\u00e4che. Diese teilt sich auf in 60 ha Acker, 20 ha Wald, 40 ha Gr\u00fcnland und 0,7 ha Gem\u00fcse- &amp; Obstgarten sowie 1,2 ha Streuobstwiesen.<\/span><\/p><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-229c2ab elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"229c2ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline_zigzag&quot;,&quot;highlighted_text&quot;:&quot;Unsere zertifizierte Landwirtschaft&quot;,&quot;highlight_animation_duration&quot;:1172,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-headline\">\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">Unsere zertifizierte Landwirtschaft<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6da3b7 elementor-widget elementor-widget-text-editor\" data-id=\"d6da3b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"1b4aa6e\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div>Unsere Landwirtschaft ist kontrolliert und zertifiziert.\u00a0Hier finden Sie die Zertifikate:<\/div><div>\u00a0<\/div><\/div><div><ul><li><strong><a href=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2026\/02\/30404-W-E-G-GmbH-2025-Zertifikat-DE-04.02.2026-180047.pdf\">Demeter-Zertifikat<\/a>\u00a0<\/strong><\/li><li><a href=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2025\/07\/ABCERT_SLG-MFG-125063014380.pdf\"><strong>ABCert-Zertifikat<\/strong><\/a><\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27038bc elementor-widget elementor-widget-spacer\" data-id=\"27038bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-472a33e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"472a33e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8d6f3a1\" data-id=\"8d6f3a1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-722f170 elementor-widget elementor-widget-spacer\" data-id=\"722f170\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ab3a74 elementor-widget elementor-widget-text-editor\" data-id=\"7ab3a74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir wollen mit gutem Beispiel vorangehen und betreiben unser <a href=\"https:\/\/alt.linden-gut.eu\/nachhaltiges-hotel-in-deutschland\/\"><strong>nachhaltiges Hotel in Deutschland<\/strong> <\/a>mit ganzheitlichem Fokus. Dazu geh\u00f6rt nat\u00fcrlich auch, eine zukunftsweisende Methode der <a href=\"https:\/\/alt.linden-gut.eu\/demeter-landwirtschaft\/\"><strong>Landwirtschaft<\/strong><\/a> zu verfolgen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-047c0ff elementor-widget elementor-widget-text-editor\" data-id=\"047c0ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/alt.linden-gut.eu\/demeter-tierhaltung\/\"><span style=\"text-decoration: underline;\">&gt;&gt; mehr dazu<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-9babb3e\" data-id=\"9babb3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fb021c elementor-widget elementor-widget-image\" data-id=\"5fb021c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alt.linden-gut.eu\/demeter-tierhaltung\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1440\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung-2048x2048.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-701\" alt=\"Nachhaltige Tierhaltung in der Demeter Landwirtschaft - Biohotel Lindengut in Dipperz\" srcset=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung.jpg 1440w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung-300x300.jpg 300w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung-1024x1024.jpg 1024w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung-150x150.jpg 150w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung-768x768.jpg 768w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f60b1cc\" data-id=\"f60b1cc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-559e70d elementor-widget elementor-widget-spacer\" data-id=\"559e70d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c06bb9 elementor-widget elementor-widget-text-editor\" data-id=\"8c06bb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/alt.linden-gut.eu\/demeter-landwirtschaft\/\"><strong>Demeter Landwirtschaft<\/strong><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc3059c elementor-widget elementor-widget-text-editor\" data-id=\"fc3059c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/alt.linden-gut.eu\/demeter-tierhaltung\/\"><span style=\"text-decoration: underline;\">mehr dazu<\/span><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-323a54c\" data-id=\"323a54c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04e6017 elementor-widget elementor-widget-spacer\" data-id=\"04e6017\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90d8e47 elementor-widget elementor-widget-image\" data-id=\"90d8e47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/elementor\/thumbs\/100prozentBio-klein-rmu3ikj20626xj5d3ijnnoft73aanzkap3fp5n5ck0.png\" title=\"100prozentBio klein\" alt=\"Logo 100 % Bio vom Acker bis zum Teller\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-793463b elementor-widget elementor-widget-spacer\" data-id=\"793463b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffb8f82 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ffb8f82\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b47f5b7\" data-id=\"b47f5b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0554d5 elementor-widget elementor-widget-image\" data-id=\"c0554d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alt.linden-gut.eu\/bio-eier-in-demeter-qualitaet\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1024\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Bio-Eier-2048x1024.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-754\" alt=\"Bio Eier aus Demeter Landwirtschaft - im Biohotel LindenGut Dipperz\" srcset=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Bio-Eier-2048x1024.jpg 2048w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Bio-Eier-300x150.jpg 300w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Bio-Eier-1024x512.jpg 1024w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Bio-Eier-768x384.jpg 768w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Bio-Eier-1536x768.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e45ed8d\" data-id=\"e45ed8d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34aadd7 elementor-widget elementor-widget-spacer\" data-id=\"34aadd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2b4418 elementor-widget elementor-widget-text-editor\" data-id=\"b2b4418\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/alt.linden-gut.eu\/bio-eier-in-demeter-qualitaet\/\"><strong>Bio-Eier in Demeter-Qualit\u00e4t<\/strong><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dad6f0 elementor-widget elementor-widget-text-editor\" data-id=\"3dad6f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/alt.linden-gut.eu\/bio-eier-in-demeter-qualitaet\/\"><span style=\"text-decoration: underline;\">&gt;&gt; mehr dazu<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-349bcce\" data-id=\"349bcce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e79a77 elementor-widget elementor-widget-image\" data-id=\"1e79a77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alt.linden-gut.eu\/bio-eier-in-demeter-qualitaet\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"1440\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung-Huehner-2048x2048.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-856\" alt=\"Biohotel Lindengut Demeter Landwirtschaft H\u00fchner\" srcset=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung-Huehner.jpg 1440w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung-Huehner-300x300.jpg 300w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung-Huehner-1024x1024.jpg 1024w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung-Huehner-150x150.jpg 150w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Tierhaltung-Huehner-768x768.jpg 768w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f72d021 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f72d021\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37b0aba\" data-id=\"37b0aba\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d187ddb elementor-widget elementor-widget-spacer\" data-id=\"d187ddb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df9d8ae elementor-widget elementor-widget-text-editor\" data-id=\"df9d8ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"f63b3d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div data-id=\"244e888\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div><h2>Demeter Landwirtschaft: Unsere Tiere<\/h2><\/div><\/div><div class=\"elementor-element elementor-element-b93c8e6 elementor-widget elementor-widget-text-editor\" data-id=\"b93c8e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-text-editor elementor-clearfix\"><p>Artgerechte bzw. Bio Tierhaltung ist uns ein besonderes Anliegen. Schlie\u00dflich soll es den tierischen Bewohnern am LindenGut gut gehen! Im Rahmen unserer biodynamischen Demeter Landwirtschaft grasen Rinder der Rassen Charolais und Aubrac auf unseren Wiesen. Saisonal tummeln sich G\u00e4nse und Pekingenten im gr\u00fcn. Nicht zu vergessen sind auch unsere Zwergziegen, die unsere zahlreichen Zweinutzungsh\u00fchner- und H\u00e4hne verantwortungsbewusst vor Raubwild bewachen. Letztere wohnen \u00fcbrigens in unserem innovativen <a href=\"https:\/\/alt.linden-gut.eu\/huehnermobil\/\"><b class=\"\">H\u00fchnermobil<\/b><\/a> \u2013 einem einzigartigen Stall zur mobilen, biologisch-dynamischen Aufzucht und H\u00fchnerhaltung!<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9437f46 elementor-invisible elementor-widget elementor-widget-button\" data-id=\"9437f46\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/alt.linden-gut.eu\/demeter-tierhaltung\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demeter Tierhaltung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70a01cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70a01cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-66432a6\" data-id=\"66432a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09412af elementor-widget elementor-widget-image\" data-id=\"09412af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alt.linden-gut.eu\/demeter-tierhaltung\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"787\" height=\"962\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Ziegen.jpg\" class=\"attachment-full size-full wp-image-873\" alt=\"Biohotel Lindengut Demeter Landwirtschaft Ziegen\" srcset=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Ziegen.jpg 787w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Ziegen-245x300.jpg 245w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Ziegen-768x939.jpg 768w\" sizes=\"(max-width: 787px) 100vw, 787px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2ab90ef\" data-id=\"2ab90ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-85402c4 elementor-widget elementor-widget-image\" data-id=\"85402c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alt.linden-gut.eu\/demeter-tierhaltung\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"787\" height=\"962\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Kuehe.jpg\" class=\"attachment-full size-full wp-image-871\" alt=\"Biohotel Lindengut Demeter Landwirtschaft K\u00fche\" srcset=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Kuehe.jpg 787w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Kuehe-245x300.jpg 245w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Kuehe-768x939.jpg 768w\" sizes=\"(max-width: 787px) 100vw, 787px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bebb1e5\" data-id=\"bebb1e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34710cc elementor-widget elementor-widget-image\" data-id=\"34710cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/alt.linden-gut.eu\/demeter-tierhaltung\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"787\" height=\"962\" src=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Huhn.jpg\" class=\"attachment-full size-full wp-image-872\" alt=\"Biohotel Lindengut Demeter Landwirtschaft Huhn\" srcset=\"https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Huhn.jpg 787w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Huhn-245x300.jpg 245w, https:\/\/alt.linden-gut.eu\/wp-content\/uploads\/2021\/05\/Biohotel-Lindengut-Demeter-Landwirtschaft-Huhn-768x939.jpg 768w\" sizes=\"(max-width: 787px) 100vw, 787px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f90316 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f90316\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e85ef67\" data-id=\"e85ef67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93a202f elementor-widget elementor-widget-spacer\" data-id=\"93a202f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d0f125 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d0f125\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c0839f\" data-id=\"2c0839f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee4f384 elementor-widget elementor-widget-spacer\" data-id=\"ee4f384\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0d82d0 elementor-widget elementor-widget-text-editor\" data-id=\"c0d82d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd121b4 elementor-widget elementor-widget-heading\" data-id=\"bd121b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-element elementor-element-1099cd6 elementor-widget elementor-widget-heading\" data-id=\"1099cd6\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-element elementor-element-b348e54 elementor-widget elementor-widget-heading\" data-id=\"b348e54\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><div data-id=\"f9bb000\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div><h2>Demeter Landwirtschaft: Unser Hofladen<\/h2><\/div><\/div><div class=\"elementor-element elementor-element-a985fbb elementor-widget elementor-widget-text-editor\" data-id=\"a985fbb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-text-editor elementor-clearfix\"><div class=\"\">Unsere biodynamische Demeter Landwirtschaft sorgt nicht nur f\u00fcr eine harmonische Atmosph\u00e4re \u2013 sie beschenkt uns auch mit allerlei qualitativ hochwertigen Demeter Produkten. So entstehen beispielsweise Brot, Eier, Fleisch und Wurst, Obst und Gem\u00fcse sowie Kr\u00e4uter, Fruchts\u00e4fte und vieles mehr. Diese bieten wir Ihnen auch in unserem Bio-<a href=\"https:\/\/alt.linden-gut.eu\/hofverkauf\/\">Hofladen<\/a>\u00a0an. Immer dienstags, donnerstags und freitags von 10:00 bis 17:00 Uhr und samstags von 7:30 bis 13:00 Uhr hei\u00dft Sie dieser am LindenGut in der Wisselsroder Strasse 1, willkommen. Unser Tipp: Probieren Sie doch mal unsere hochwertigen Nudelprodukte, die es in vielen verlockenden Sorten.<\/div><div class=\"\">Seit November 2025 k\u00f6nnen Sie auch in der Fuldaer Innenstadt unsere Produkte in unserem eigenen LindenGut Stadtladen kennenlernen &#8211; Kommen Sie gerne vorbei!<\/div><div class=\"\">Von Dienstag (10-18 Uhr) bis Samstag (9-13 Uhr) hat der Stadtladen f\u00fcr Sie ge\u00f6ffnet.<\/div><div class=\"\">Konnten wir Ihnen einen Einblick in unsere biologisch-dynamische Wirtschaftsweise geben? Sollten Sie weitere Fragen zu unserem Hof und unserem <a href=\"https:\/\/alt.linden-gut.eu\/biohotel-hessen\/\">Biohotel in Hessen<\/a> haben oder unser wunderbares Kleinod in der hessischen Rh\u00f6n n\u00e4her kennenlernen wollen, freuen wir uns sehr, von Ihnen zu h\u00f6ren!<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da408ea elementor-invisible elementor-widget elementor-widget-button\" data-id=\"da408ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/alt.linden-gut.eu\/hofladen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hofladen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0a5acb elementor-widget elementor-widget-spacer\" data-id=\"a0a5acb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-864956a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"864956a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-94e1822\" data-id=\"94e1822\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e475bf3 elementor-widget elementor-widget-spacer\" data-id=\"e475bf3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Demeter LandwirtschaftUnseren Betrieb mit 100 % zertifizierter Bio-Qualit\u00e4t zu f\u00fchren, war uns schon lange ein gro\u00dfes Anliegen. Doch wir wollten noch einen Schritt weiter gehen. Daher beschlossen wir, eine biodynamische Wirtschaftsweise anzuwenden und alles in zertifizierter Demeter-Qualit\u00e4t anzubieten. Demeter Landwirtschaft Was ist \u00fcberhaupt eine Demeter Landwirtschaft? Die Demeter Landwirtschaft am BIO HOTEL LindenGut wird nach [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-69","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Demeter Landwirtschaft mit Siegel im BIO HOTEL LindenGut<\/title>\n<meta name=\"description\" content=\"Unsere Demeter Landwirtschaft ist u.a. Hauptlieferant f\u00fcr unser Fr\u00fchst\u00fcck, Eigenmarken und Veranstaltungen \u27a8 Jetzt entdecken!\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Demeter Landwirtschaft mit Siegel im BIO HOTEL LindenGut\" \/>\n<meta property=\"og:description\" content=\"Unsere Demeter Landwirtschaft ist u.a. Hauptlieferant f\u00fcr unser Fr\u00fchst\u00fcck, Eigenmarken und Veranstaltungen \u27a8 Jetzt entdecken!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alt.linden-gut.eu\/de\/demeter-landwirtschaft\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LindenGutDipperz\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-16T13:18:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/linden-gut.eu\/wp-content\/uploads\/2021\/04\/Biohotel-Lindengut-Nachhaltiges-Hotel-3.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/demeter-landwirtschaft\\\/\",\"url\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/demeter-landwirtschaft\\\/\",\"name\":\"Demeter Landwirtschaft mit Siegel im BIO HOTEL LindenGut\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/demeter-landwirtschaft\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/demeter-landwirtschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/linden-gut.eu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Biohotel-Lindengut-Nachhaltiges-Hotel-3.jpg\",\"datePublished\":\"2021-04-27T09:33:55+00:00\",\"dateModified\":\"2026-02-16T13:18:59+00:00\",\"description\":\"Unsere Demeter Landwirtschaft ist u.a. Hauptlieferant f\u00fcr unser Fr\u00fchst\u00fcck, Eigenmarken und Veranstaltungen \u27a8 Jetzt entdecken!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/demeter-landwirtschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/demeter-landwirtschaft\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/demeter-landwirtschaft\\\/#primaryimage\",\"url\":\"https:\\\/\\\/linden-gut.eu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Biohotel-Lindengut-Nachhaltiges-Hotel-3.jpg\",\"contentUrl\":\"https:\\\/\\\/linden-gut.eu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Biohotel-Lindengut-Nachhaltiges-Hotel-3.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/demeter-landwirtschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Demeter Landwirtschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/\",\"name\":\"LindenGut\",\"description\":\"Nachhaltiger Genuss und Komfort \u2013 Bio-Qualit\u00e4t in Hotel, Herberge, Hofladen und mehr.\",\"publisher\":{\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/#organization\",\"name\":\"LindenGut GmbH & Co. KG\",\"url\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/linden-gut.eu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Biohotel-Lindengut-Favicon.png\",\"contentUrl\":\"https:\\\/\\\/linden-gut.eu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Biohotel-Lindengut-Favicon.png\",\"width\":712,\"height\":712,\"caption\":\"LindenGut GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/alt.linden-gut.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LindenGutDipperz\",\"https:\\\/\\\/www.instagram.com\\\/lindengut_biohotel\\\/\",\"http:\\\/\\\/www.youtube.com\\\/@lindengutwegweiser2448\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Demeter Landwirtschaft mit Siegel im BIO HOTEL LindenGut","description":"Unsere Demeter Landwirtschaft ist u.a. Hauptlieferant f\u00fcr unser Fr\u00fchst\u00fcck, Eigenmarken und Veranstaltungen \u27a8 Jetzt entdecken!","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Demeter Landwirtschaft mit Siegel im BIO HOTEL LindenGut","og_description":"Unsere Demeter Landwirtschaft ist u.a. Hauptlieferant f\u00fcr unser Fr\u00fchst\u00fcck, Eigenmarken und Veranstaltungen \u27a8 Jetzt entdecken!","og_url":"https:\/\/alt.linden-gut.eu\/de\/demeter-landwirtschaft\/","article_publisher":"https:\/\/www.facebook.com\/LindenGutDipperz","article_modified_time":"2026-02-16T13:18:59+00:00","og_image":[{"url":"https:\/\/linden-gut.eu\/wp-content\/uploads\/2021\/04\/Biohotel-Lindengut-Nachhaltiges-Hotel-3.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alt.linden-gut.eu\/de\/demeter-landwirtschaft\/","url":"https:\/\/alt.linden-gut.eu\/de\/demeter-landwirtschaft\/","name":"Demeter Landwirtschaft mit Siegel im BIO HOTEL LindenGut","isPartOf":{"@id":"https:\/\/alt.linden-gut.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alt.linden-gut.eu\/de\/demeter-landwirtschaft\/#primaryimage"},"image":{"@id":"https:\/\/alt.linden-gut.eu\/de\/demeter-landwirtschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/linden-gut.eu\/wp-content\/uploads\/2021\/04\/Biohotel-Lindengut-Nachhaltiges-Hotel-3.jpg","datePublished":"2021-04-27T09:33:55+00:00","dateModified":"2026-02-16T13:18:59+00:00","description":"Unsere Demeter Landwirtschaft ist u.a. Hauptlieferant f\u00fcr unser Fr\u00fchst\u00fcck, Eigenmarken und Veranstaltungen \u27a8 Jetzt entdecken!","breadcrumb":{"@id":"https:\/\/alt.linden-gut.eu\/de\/demeter-landwirtschaft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alt.linden-gut.eu\/de\/demeter-landwirtschaft\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/alt.linden-gut.eu\/de\/demeter-landwirtschaft\/#primaryimage","url":"https:\/\/linden-gut.eu\/wp-content\/uploads\/2021\/04\/Biohotel-Lindengut-Nachhaltiges-Hotel-3.jpg","contentUrl":"https:\/\/linden-gut.eu\/wp-content\/uploads\/2021\/04\/Biohotel-Lindengut-Nachhaltiges-Hotel-3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/alt.linden-gut.eu\/de\/demeter-landwirtschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/alt.linden-gut.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Demeter Landwirtschaft"}]},{"@type":"WebSite","@id":"https:\/\/alt.linden-gut.eu\/de\/#website","url":"https:\/\/alt.linden-gut.eu\/de\/","name":"LindenGut","description":"Nachhaltiger Genuss und Komfort \u2013 Bio-Qualit\u00e4t in Hotel, Herberge, Hofladen und mehr.","publisher":{"@id":"https:\/\/alt.linden-gut.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alt.linden-gut.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/alt.linden-gut.eu\/de\/#organization","name":"LindenGut GmbH & Co. KG","url":"https:\/\/alt.linden-gut.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/alt.linden-gut.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/linden-gut.eu\/wp-content\/uploads\/2021\/04\/Biohotel-Lindengut-Favicon.png","contentUrl":"https:\/\/linden-gut.eu\/wp-content\/uploads\/2021\/04\/Biohotel-Lindengut-Favicon.png","width":712,"height":712,"caption":"LindenGut GmbH & Co. KG"},"image":{"@id":"https:\/\/alt.linden-gut.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LindenGutDipperz","https:\/\/www.instagram.com\/lindengut_biohotel\/","http:\/\/www.youtube.com\/@lindengutwegweiser2448"]}]}},"_links":{"self":[{"href":"https:\/\/alt.linden-gut.eu\/de\/wp-json\/wp\/v2\/pages\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alt.linden-gut.eu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alt.linden-gut.eu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alt.linden-gut.eu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alt.linden-gut.eu\/de\/wp-json\/wp\/v2\/comments?post=69"}],"version-history":[{"count":4,"href":"https:\/\/alt.linden-gut.eu\/de\/wp-json\/wp\/v2\/pages\/69\/revisions"}],"predecessor-version":[{"id":11154,"href":"https:\/\/alt.linden-gut.eu\/de\/wp-json\/wp\/v2\/pages\/69\/revisions\/11154"}],"wp:attachment":[{"href":"https:\/\/alt.linden-gut.eu\/de\/wp-json\/wp\/v2\/media?parent=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}